{"id":5195,"date":"2025-10-26T18:06:10","date_gmt":"2025-10-26T18:06:10","guid":{"rendered":"https:\/\/waboom.net\/?post_type=docs&#038;p=5195"},"modified":"2025-10-26T18:06:12","modified_gmt":"2025-10-26T18:06:12","password":"","slug":"wa-boom-inbox-overview","status":"publish","type":"docs","link":"https:\/\/waboom.net\/fr_be\/docs\/wa-boom-inbox-overview\/","title":{"rendered":"Aper\u00e7u de la bo\u00eete de r\u00e9ception WA Boom"},"content":{"rendered":"<p>La bo\u00eete de r\u00e9ception WA Boom est votre espace de travail central pour g\u00e9rer les conversations clients sur WhatsApp.<br>Depuis un seul \u00e9cran, vous pouvez consulter les conversations entrantes, les attribuer aux membres de l&#039;\u00e9quipe, ajouter des \u00e9tiquettes, activer les bots et conserver une visibilit\u00e9 compl\u00e8te sur chaque interaction.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"498\" src=\"https:\/\/waboom.net\/wp-content\/uploads\/2025\/10\/waboom-whatsapp-inbox-1024x498.png\" alt=\"\" class=\"wp-image-5196\" title=\"\" srcset=\"https:\/\/waboom.net\/wp-content\/uploads\/2025\/10\/waboom-whatsapp-inbox-1024x498.png 1024w, https:\/\/waboom.net\/wp-content\/uploads\/2025\/10\/waboom-whatsapp-inbox-300x146.png 300w, https:\/\/waboom.net\/wp-content\/uploads\/2025\/10\/waboom-whatsapp-inbox-768x374.png 768w, https:\/\/waboom.net\/wp-content\/uploads\/2025\/10\/waboom-whatsapp-inbox-1536x747.png 1536w, https:\/\/waboom.net\/wp-content\/uploads\/2025\/10\/waboom-whatsapp-inbox-360x175.png 360w, https:\/\/waboom.net\/wp-content\/uploads\/2025\/10\/waboom-whatsapp-inbox.png 1786w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Objectif de la bo\u00eete de r\u00e9ception<\/h2>\n\n\n\n<p>La bo\u00eete de r\u00e9ception rassemble toutes les conversations WhatsApp dans un environnement unique et collaboratif.<br>Cela permet \u00e0 votre \u00e9quipe de\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>R\u00e9pondre aux messages provenant de num\u00e9ros WhatsApp v\u00e9rifi\u00e9s.<\/li>\n\n\n\n<li>Attribuer ou r\u00e9attribuer des conversations aux agents en temps r\u00e9el.<\/li>\n\n\n\n<li>Activez les r\u00e9ponses automatis\u00e9es et les bots IA.<\/li>\n\n\n\n<li>Organisez vos contacts \u00e0 l&#039;aide d&#039;\u00e9tiquettes ou de tags pour la segmentation.<\/li>\n\n\n\n<li>Conservez un profil de contact d\u00e9taill\u00e9 avec des notes et un historique.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Principales sections de la bo\u00eete de r\u00e9ception<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1. Panneau de la liste de discussion<\/h3>\n\n\n\n<p>Situ\u00e9 \u00e0 gauche, ce panneau affiche toutes les conversations class\u00e9es par cat\u00e9gorie. <strong>Tous<\/strong>, <strong>Le mien<\/strong>, ou <strong>Non attribu\u00e9<\/strong>.<br>Tu peux:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Filtrer par \u00e9tiquettes ou tags.<\/li>\n\n\n\n<li>Rechercher un contact ou un num\u00e9ro de t\u00e9l\u00e9phone.<\/li>\n\n\n\n<li>Identifiez rapidement les conversations non lues ou nouvellement attribu\u00e9es.<\/li>\n<\/ul>\n\n\n\n<p><strong>Conseil:<\/strong> Surveillez r\u00e9guli\u00e8rement la section \u201c\u00a0Non attribu\u00e9s\u00a0\u201d afin de garantir qu&#039;aucune demande client ne reste sans r\u00e9ponse.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Fen\u00eatre de conversation<\/h3>\n\n\n\n<p>La zone centrale affiche l&#039;historique complet des conversations avec le contact s\u00e9lectionn\u00e9.<br>Vous pouvez consulter les messages, envoyer des r\u00e9ponses, joindre des fichiers multim\u00e9dias et suivre l&#039;\u00e9tat de la livraison.<\/p>\n\n\n\n<p>Lorsqu&#039;un contact devient inactif, vous pouvez voir une notification telle que\u00a0: <em>\u201c Vous ne pouvez pas r\u00e9pondre ; ils doivent r\u00e9pondre pour que la conversation puisse commencer. \u201d<\/em><br>Ce message signifie que le d\u00e9lai de r\u00e9ponse de 24 heures sur WhatsApp Business a expir\u00e9. Pour relancer la conversation, envoyez un mod\u00e8le de message approuv\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Panneau d&#039;informations de contact<\/h3>\n\n\n\n<p>\u00c0 droite, vous trouverez des informations d\u00e9taill\u00e9es sur le contact s\u00e9lectionn\u00e9, notamment\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nom, num\u00e9ro de t\u00e9l\u00e9phone, adresse courriel et langue<\/strong><\/li>\n\n\n\n<li><strong>Membre de l&#039;\u00e9quipe d\u00e9sign\u00e9<\/strong> d\u00e9rouler<\/li>\n\n\n\n<li><strong>Les commutateurs AI Bot et Reply Bot sont activ\u00e9s<\/strong><\/li>\n\n\n\n<li><strong>\u00c9tiquettes\/Tags<\/strong> cat\u00e9goriser le contact<\/li>\n\n\n\n<li><strong>Notes<\/strong> pour usage interne<\/li>\n<\/ul>\n\n\n\n<p>Cliquez <strong>Modifier les coordonn\u00e9es<\/strong> mettre \u00e0 jour ou corriger toute information.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Attribuer une conversation<\/h2>\n\n\n\n<p>Pour d\u00e9l\u00e9guer une conversation\u00a0:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ouvrir le contact.<\/li>\n\n\n\n<li>Dans le <em>Attribuer un membre de l&#039;\u00e9quipe<\/em> Dans cette section, s\u00e9lectionnez un agent dans la liste d\u00e9roulante.<\/li>\n\n\n\n<li>Cliquez <strong>Sauvegarder<\/strong>.<\/li>\n<\/ol>\n\n\n\n<p>Les agents d\u00e9sign\u00e9s verront la conversation dans leur vue \u201c\u00a0Mienne\u00a0\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Utilisation des bots et de l&#039;automatisation<\/h2>\n\n\n\n<p>Activer <strong>Bot IA<\/strong> pour permettre au syst\u00e8me de g\u00e9n\u00e9rer des r\u00e9ponses intelligentes en fonction du contexte.<br>Activer <strong>Bot de r\u00e9ponse<\/strong> envoyer des r\u00e9ponses pr\u00e9d\u00e9finies ou des accus\u00e9s de r\u00e9ception rapides.<\/p>\n\n\n\n<p>Les chatbots r\u00e9duisent la charge de travail et garantissent \u00e0 chaque client une r\u00e9ponse rapide, m\u00eame en dehors des heures ouvrables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tiquetage et marquage<\/h2>\n\n\n\n<p>Les \u00e9tiquettes et les tags permettent d&#039;organiser les contacts par centre d&#039;int\u00e9r\u00eat, \u00e9tape ou type de campagne.<br>Par exemple:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Conduit<\/em><\/li>\n\n\n\n<li><em>Clients actifs<\/em><\/li>\n\n\n\n<li><em>Tickets d&#039;assistance<\/em><\/li>\n<\/ul>\n\n\n\n<p>Pour ajouter des \u00e9tiquettes, ouvrez le profil du contact, s\u00e9lectionnez ou saisissez une nouvelle \u00e9tiquette, puis cliquez sur <strong>Mise \u00e0 jour<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notes et collaboration<\/h2>\n\n\n\n<p>La section Notes permet aux membres de l&#039;\u00e9quipe d&#039;enregistrer des d\u00e9tails importants sans les envoyer au client.<br>Cela garantit une collaboration fluide entre les \u00e9quipes et les services.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notifications courantes et leur signification<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00c9chec de l&#039;envoi du message<\/strong> \u2013 Le message n&#039;a pas pu \u00eatre remis car le num\u00e9ro de l&#039;utilisateur fait partie d&#039;une exp\u00e9rience WhatsApp ou la session de 24 heures est termin\u00e9e.<\/li>\n\n\n\n<li><strong>Conversation non attribu\u00e9e<\/strong> \u2013 Aucun agent n&#039;est actuellement responsable de cette conversation. Attribuez-la pour assurer un suivi.<\/li>\n\n\n\n<li><strong>Bot IA actif<\/strong> \u2013 Indique que l&#039;automatisation g\u00e8re la r\u00e9ponse initiale.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Meilleures pratiques<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gardez votre bo\u00eete de r\u00e9ception organis\u00e9e en utilisant des libell\u00e9s coh\u00e9rents.<\/li>\n\n\n\n<li>Examinez quotidiennement les conversations inactives ou ferm\u00e9es.<\/li>\n\n\n\n<li>Utilisez des mod\u00e8les pour reprendre contact au-del\u00e0 de la fen\u00eatre de 24 heures.<\/li>\n\n\n\n<li>Suivre r\u00e9guli\u00e8rement les performances et les temps de r\u00e9ponse des agents.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>The WA Boom Inbox is your central workspace for managing customer conversations on WhatsApp.From one unified screen, you can view incoming chats, assign them to team members, add labels, enable bots, and maintain full visibility into every interaction. Purpose of the Inbox The Inbox brings all WhatsApp conversations into a single, collaborative environment.It allows your&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"doc_category":[39],"doc_tag":[],"class_list":["post-5195","docs","type-docs","status-publish","hentry","doc_category-installation"],"year_month":"2026-05","word_count":500,"total_views":"13590","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Usman","author_nicename":"usman","author_url":"https:\/\/waboom.net\/fr_be\/author\/usman\/"},"doc_category_info":[{"term_name":"Installation","term_url":"https:\/\/waboom.net\/fr_be\/docs-category\/installation\/"}],"doc_tag_info":[],"knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/docs\/5195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/comments?post=5195"}],"version-history":[{"count":0,"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/docs\/5195\/revisions"}],"wp:attachment":[{"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/media?parent=5195"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/doc_category?post=5195"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/waboom.net\/fr_be\/wp-json\/wp\/v2\/doc_tag?post=5195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}